{"id":17886,"date":"2025-05-18T12:14:38","date_gmt":"2025-05-18T19:14:38","guid":{"rendered":"https:\/\/yorkriteca.org\/royal-arch\/event\/whittier-bellflower-3-way-reception\/"},"modified":"2026-03-07T04:49:10","modified_gmt":"2026-03-07T12:49:10","slug":"whittier-bellflower-3-way-reception","status":"publish","type":"tribe_events","link":"https:\/\/yorkriteca.org\/royal-arch\/event\/whittier-bellflower-3-way-reception\/","title":{"rendered":"Whittier\/Bellflower 3 Way Reception"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-17886","tribe_events","type-tribe_events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Whittier\/Bellflower 3 Way Reception - Royal Arch Masons of California<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yorkriteca.org\/royal-arch\/event\/whittier-bellflower-3-way-reception\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Whittier\/Bellflower 3 Way Reception - Royal Arch Masons of California\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yorkriteca.org\/royal-arch\/event\/whittier-bellflower-3-way-reception\/\" \/>\n<meta property=\"og:site_name\" content=\"Royal Arch Masons of California\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-07T12:49:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/event\\\/whittier-bellflower-3-way-reception\\\/\",\"url\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/event\\\/whittier-bellflower-3-way-reception\\\/\",\"name\":\"Whittier\\\/Bellflower 3 Way Reception - Royal Arch Masons of California\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/#website\"},\"datePublished\":\"2025-05-18T19:14:38+00:00\",\"dateModified\":\"2026-03-07T12:49:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/event\\\/whittier-bellflower-3-way-reception\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/event\\\/whittier-bellflower-3-way-reception\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/event\\\/whittier-bellflower-3-way-reception\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Whittier\\\/Bellflower 3 Way Reception\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/#website\",\"url\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/\",\"name\":\"Royal Arch Masons of California\",\"description\":\"Grand Chapter\",\"publisher\":{\"@id\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/#organization\",\"name\":\"Grand Chapter Royal Arch Masons of California\",\"url\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/08\\\/GYRCA-logo-ram.png\",\"contentUrl\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/08\\\/GYRCA-logo-ram.png\",\"width\":1050,\"height\":210,\"caption\":\"Grand Chapter Royal Arch Masons of California\"},\"image\":{\"@id\":\"https:\\\/\\\/yorkriteca.org\\\/royal-arch\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Whittier\/Bellflower 3 Way Reception - Royal Arch Masons of California","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yorkriteca.org\/royal-arch\/event\/whittier-bellflower-3-way-reception\/","og_locale":"en_US","og_type":"article","og_title":"Whittier\/Bellflower 3 Way Reception - Royal Arch Masons of California","og_url":"https:\/\/yorkriteca.org\/royal-arch\/event\/whittier-bellflower-3-way-reception\/","og_site_name":"Royal Arch Masons of California","article_modified_time":"2026-03-07T12:49:10+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/yorkriteca.org\/royal-arch\/event\/whittier-bellflower-3-way-reception\/","url":"https:\/\/yorkriteca.org\/royal-arch\/event\/whittier-bellflower-3-way-reception\/","name":"Whittier\/Bellflower 3 Way Reception - Royal Arch Masons of California","isPartOf":{"@id":"https:\/\/yorkriteca.org\/royal-arch\/#website"},"datePublished":"2025-05-18T19:14:38+00:00","dateModified":"2026-03-07T12:49:10+00:00","breadcrumb":{"@id":"https:\/\/yorkriteca.org\/royal-arch\/event\/whittier-bellflower-3-way-reception\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/yorkriteca.org\/royal-arch\/event\/whittier-bellflower-3-way-reception\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/yorkriteca.org\/royal-arch\/event\/whittier-bellflower-3-way-reception\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/yorkriteca.org\/royal-arch\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/yorkriteca.org\/royal-arch\/events\/"},{"@type":"ListItem","position":3,"name":"Whittier\/Bellflower 3 Way Reception"}]},{"@type":"WebSite","@id":"https:\/\/yorkriteca.org\/royal-arch\/#website","url":"https:\/\/yorkriteca.org\/royal-arch\/","name":"Royal Arch Masons of California","description":"Grand Chapter","publisher":{"@id":"https:\/\/yorkriteca.org\/royal-arch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yorkriteca.org\/royal-arch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/yorkriteca.org\/royal-arch\/#organization","name":"Grand Chapter Royal Arch Masons of California","url":"https:\/\/yorkriteca.org\/royal-arch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/yorkriteca.org\/royal-arch\/#\/schema\/logo\/image\/","url":"https:\/\/yorkriteca.org\/royal-arch\/wp-content\/uploads\/sites\/2\/2023\/08\/GYRCA-logo-ram.png","contentUrl":"https:\/\/yorkriteca.org\/royal-arch\/wp-content\/uploads\/sites\/2\/2023\/08\/GYRCA-logo-ram.png","width":1050,"height":210,"caption":"Grand Chapter Royal Arch Masons of California"},"image":{"@id":"https:\/\/yorkriteca.org\/royal-arch\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/yorkriteca.org\/royal-arch\/wp-json\/wp\/v2\/tribe_events\/17886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yorkriteca.org\/royal-arch\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/yorkriteca.org\/royal-arch\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/yorkriteca.org\/royal-arch\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/yorkriteca.org\/royal-arch\/wp-json\/wp\/v2\/tribe_events\/17886\/revisions"}],"wp:attachment":[{"href":"https:\/\/yorkriteca.org\/royal-arch\/wp-json\/wp\/v2\/media?parent=17886"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yorkriteca.org\/royal-arch\/wp-json\/wp\/v2\/tags?post=17886"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/yorkriteca.org\/royal-arch\/wp-json\/wp\/v2\/tribe_events_cat?post=17886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}